{"id":20782,"date":"2023-05-16T18:32:17","date_gmt":"2023-05-16T21:32:17","guid":{"rendered":"http:\/\/www.sindipetroba.org.br\/2019\/?p=20782"},"modified":"2023-05-16T18:32:17","modified_gmt":"2023-05-16T21:32:17","slug":"sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro","status":"publish","type":"post","link":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/","title":{"rendered":"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro"},"content":{"rendered":"<p><strong>A diretoria do Sindipetro-Ba se reuniu com o presidente da Transpetro nesta ter\u00e7a-feira (16), para discutir pautas de interesse da categoria. <\/strong><\/p>\n<p>Na busca por um di\u00e1logo aberto com a empresa, Elisabete Sacramento, diretora financeira do Sindipetro mediou a reuni\u00e3o e aproveitou a oportunidade para entregar uma carta de reivindica\u00e7\u00e3o ao Presidente da Transpetro, Sergio Bacci.<br \/>\nA diretora que tamb\u00e9m \u00e9 empregada da Transpetro h\u00e1 14 anos, mencionou que n\u00e3o houve transpar\u00eancia sobre o novo contrato da empresa e explicou que existem cobran\u00e7as indevidas sendo feitas aos trabalhadores. Elisabete tamb\u00e9m refor\u00e7ou a preocupa\u00e7\u00e3o do sindicato com a falta de medidas de seguran\u00e7a em alguns setores da empresa e comentou que \u201ca for\u00e7a de trabalho ficou mais vulner\u00e1vel pela necessidade de cobran\u00e7a da empresa por produtividade, sem garantir a autoridade t\u00e9cnica de quem opera o terminal\u201d.<br \/>\nQuem tamb\u00e9m esteve no encontro foi a diretora executiva do Sindipetro, tamb\u00e9m funcion\u00e1ria da Transpetro, Jailza Barbosa. Ela questionou sobre a cultura que se estabeleceu na empresa desde que a Petrobr\u00e1s saiu e revelou a falta de di\u00e1logo dos \u00faltimos anos. \u201cN\u00e3o foi levado em conta o impacto hist\u00f3rico e econ\u00f4mico da privatiza\u00e7\u00e3o da empresa na Bahia, apontamos riscos evidentes e n\u00e3o somos ouvidos e n\u00e3o temos a quem recorrer. A resposta \u00e9 sempre: &#8220;temos que manter produtividade, temos que garantir esse contrato&#8221;, explicou a diretora.<br \/>\nAndr\u00e9 Ara\u00fajo, diretor do Sindipetro-Ba, pontuou a necessidade de oferecer estrutura adequada aos trabalhadores e de manter uma clareza sobre o que a nova gest\u00e3o est\u00e1 prevendo para a empresa daqui pra frente.<br \/>\nDeivyd Bacelar, representando a Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP), participou da conversa, comemorou a retomada do di\u00e1logo da Transpetro com o Sindipetro na Bahia e pediu mais transpar\u00eancia com os acordos internacionais, j\u00e1 que eles adquiriram a performance da empresa no estado.<\/p>\n","protected":false},"excerpt":{"rendered":"A diretoria do Sindipetro-Ba se reuniu com o presidente da Transpetro nesta ter\u00e7a-feira (16), para discutir pautas de interesse da categoria. Na busca por um di\u00e1logo aberto com a empresa, Elisabete Sacramento, diretora financeira do Sindipetro mediou a reuni\u00e3o e aproveitou a oportunidade para entregar uma carta de reivindica\u00e7\u00e3o ao Presidente da Transpetro, Sergio Bacci&#8230;. <a class=\"view-article\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/\">Ver artigo<\/a>","protected":false},"author":4,"featured_media":20783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-20782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"A diretoria do Sindipetro-Ba se reuniu com o presidente da Transpetro nesta ter\u00e7a-feira (16), para discutir pautas de interesse da categoria. Na busca por um di\u00e1logo aberto com a empresa, Elisabete Sacramento, diretora financeira do Sindipetro mediou a reuni\u00e3o e aproveitou a oportunidade para entregar uma carta de reivindica\u00e7\u00e3o ao Presidente da Transpetro, Sergio Bacci.... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T21:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/\"},\"author\":{\"name\":\"ASCOM\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\"},\"headline\":\"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro\",\"datePublished\":\"2023-05-16T21:32:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/\"},\"wordCount\":333,\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg\",\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/\",\"name\":\"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro - Sindipetro BA\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg\",\"datePublished\":\"2023-05-16T21:32:17+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg\",\"width\":1160,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\",\"name\":\"ASCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"caption\":\"ASCOM\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/","og_locale":"pt_BR","og_type":"article","og_title":"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro - Sindipetro BA","og_description":"A diretoria do Sindipetro-Ba se reuniu com o presidente da Transpetro nesta ter\u00e7a-feira (16), para discutir pautas de interesse da categoria. Na busca por um di\u00e1logo aberto com a empresa, Elisabete Sacramento, diretora financeira do Sindipetro mediou a reuni\u00e3o e aproveitou a oportunidade para entregar uma carta de reivindica\u00e7\u00e3o ao Presidente da Transpetro, Sergio Bacci.... Ver artigo","og_url":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2023-05-16T21:32:17+00:00","og_image":[{"width":1160,"height":522,"url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg","type":"image\/jpeg"}],"author":"ASCOM","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#article","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/"},"author":{"name":"ASCOM","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c"},"headline":"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro","datePublished":"2023-05-16T21:32:17+00:00","mainEntityOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/"},"wordCount":333,"publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg","articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/","name":"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro - Sindipetro BA","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#primaryimage"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg","datePublished":"2023-05-16T21:32:17+00:00","breadcrumb":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#primaryimage","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-16-at-17.57.31.jpeg","width":1160,"height":522},{"@type":"BreadcrumbList","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-entrega-carta-de-reivindicacao-a-presidente-da-transpetro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Sindipetro-Ba entrega carta de reivindica\u00e7\u00e3o a presidente da Transpetro"}]},{"@type":"WebSite","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website","url":"http:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"http:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c","name":"ASCOM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","caption":"ASCOM"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=20782"}],"version-history":[{"count":1,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20782\/revisions"}],"predecessor-version":[{"id":20784,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20782\/revisions\/20784"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/20783"}],"wp:attachment":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=20782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=20782"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=20782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}