{"id":20880,"date":"2023-05-25T10:04:24","date_gmt":"2023-05-25T13:04:24","guid":{"rendered":"http:\/\/www.sindipetroba.org.br\/2019\/?p=20880"},"modified":"2023-05-25T10:04:24","modified_gmt":"2023-05-25T13:04:24","slug":"associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir","status":"publish","type":"post","link":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/","title":{"rendered":"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR"},"content":{"rendered":"<p>An\u00e1lise tribut\u00e1ria ser\u00e1 feita, caso a caso, por assessoria contratada pelo Sindipetro<br \/>\nSe voc\u00ea \u00e9 petroleiro (a) aposentado (a) e sofre de alguma doen\u00e7a grave prevista na Lei 7.713\/88, voc\u00ea pode ficar isento de pagar o imposto de renda e ainda receber a restitui\u00e7\u00e3o do tributo dos \u00faltimos cinco anos.<\/p>\n<p>Para orientar e garantir o direito da categoria, de forma administrativa, o Sindipetro Bahia fechou conv\u00eanio com a 3M assessoria.<\/p>\n<p>A empresa vai realizar an\u00e1lise tribut\u00e1ria dos associados do Sindipetro dos \u00faltimos cinco anos para apurar se h\u00e1 valores pagos indevidamente sujeitos a recupera\u00e7\u00e3o. Ap\u00f3s an\u00e1lise, se houver valores a serem restitu\u00eddos, vai efetuar todos os procedimentos para recupera\u00e7\u00e3o desses cr\u00e9ditos diretamente na conta corrente do associado da entidade sindical.<\/p>\n<p>No rol das doen\u00e7as elencadas pela Lei 7.713\/88 est\u00e3o tuberculose ativa; aliena\u00e7\u00e3o mental (Alzheimer, Dem\u00eancia, Esquizofrenia, etc.); esclerose m\u00faltipla; neoplasia maligna (C\u00e2ncer, inclusive casos de pacientes curados); cardiopatia grave (Infarto, Ponte de Safena, Ponte de Mam\u00e1ria, Stents, Angioplastia, etc.); doen\u00e7a de Parkinson; entre outras. As mol\u00e9stias profissionais e o acidente de trabalho tamb\u00e9m s\u00e3o condi\u00e7\u00f5es que garantem a isen\u00e7\u00e3o de IR pela referida Lei.<\/p>\n<p>Roteiro de atendimento aos associados nas subsedes do Sindipetro:<\/p>\n<p>Feira de Santana \u2013 26\/05, sexta-feira, \u00e0s 9h<\/p>\n<p>Catu \u2013 01\/06, quinta-feira, \u00e0s 9h<\/p>\n<p>S\u00e3o Sebasti\u00e3o do Pass\u00e9 \u2013 01\/06, quinta-feira, \u00e0s 14h<\/p>\n<p>Candeias \u2013 02\/06, sexta-feira, \u00e0s 9h<\/p>\n<p>Madre de Deus \u2013 02\/06, sexta-feira, \u00e0s 11h<\/p>\n<p>S\u00e3o Francisco do Conde \u2013 02\/06, sexta-feira, \u00e0s 14h<\/p>\n<p>A empresa j\u00e1 passou pela cidade de Alagoinhas, onde orientou os aposentados e pensionistas.<\/p>\n<p>Este \u00e9 mais um servi\u00e7o oferecido pelo Sindipetro Bahia para atender as necessidades dos nossos associados (as) aposentados (as) e aposentadas da categoria.<\/p>\n<p>Fonte- Imprensa Sindipetro Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"An\u00e1lise tribut\u00e1ria ser\u00e1 feita, caso a caso, por assessoria contratada pelo Sindipetro Se voc\u00ea \u00e9 petroleiro (a) aposentado (a) e sofre de alguma doen\u00e7a grave prevista na Lei 7.713\/88, voc\u00ea pode ficar isento de pagar o imposto de renda e ainda receber a restitui\u00e7\u00e3o do tributo dos \u00faltimos cinco anos. Para orientar e garantir o&#8230; <a class=\"view-article\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/\">Ver artigo<\/a>","protected":false},"author":4,"featured_media":20881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-20880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"An\u00e1lise tribut\u00e1ria ser\u00e1 feita, caso a caso, por assessoria contratada pelo Sindipetro Se voc\u00ea \u00e9 petroleiro (a) aposentado (a) e sofre de alguma doen\u00e7a grave prevista na Lei 7.713\/88, voc\u00ea pode ficar isento de pagar o imposto de renda e ainda receber a restitui\u00e7\u00e3o do tributo dos \u00faltimos cinco anos. Para orientar e garantir o... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-25T13:04:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/\"},\"author\":{\"name\":\"ASCOM\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\"},\"headline\":\"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR\",\"datePublished\":\"2023-05-25T13:04:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg\",\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/\",\"name\":\"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR - Sindipetro BA\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg\",\"datePublished\":\"2023-05-25T13:04:24+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\",\"name\":\"ASCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"caption\":\"ASCOM\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/","og_locale":"pt_BR","og_type":"article","og_title":"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR - Sindipetro BA","og_description":"An\u00e1lise tribut\u00e1ria ser\u00e1 feita, caso a caso, por assessoria contratada pelo Sindipetro Se voc\u00ea \u00e9 petroleiro (a) aposentado (a) e sofre de alguma doen\u00e7a grave prevista na Lei 7.713\/88, voc\u00ea pode ficar isento de pagar o imposto de renda e ainda receber a restitui\u00e7\u00e3o do tributo dos \u00faltimos cinco anos. Para orientar e garantir o... Ver artigo","og_url":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2023-05-25T13:04:24+00:00","og_image":[{"width":1200,"height":1200,"url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg","type":"image\/jpeg"}],"author":"ASCOM","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#article","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/"},"author":{"name":"ASCOM","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c"},"headline":"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR","datePublished":"2023-05-25T13:04:24+00:00","mainEntityOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/"},"wordCount":308,"publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg","articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/","name":"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR - Sindipetro BA","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#primaryimage"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg","datePublished":"2023-05-25T13:04:24+00:00","breadcrumb":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#primaryimage","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-25-at-09.45.56.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"http:\/\/www.sindipetroba.org.br\/2019\/associados-do-sindipetro-ba-portadores-de-doencas-graves-podem-ter-isencao-do-ir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Associados do Sindipetro-Ba, portadores de doen\u00e7as graves, podem ter isen\u00e7\u00e3o do IR"}]},{"@type":"WebSite","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website","url":"http:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"http:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c","name":"ASCOM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","caption":"ASCOM"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=20880"}],"version-history":[{"count":1,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20880\/revisions"}],"predecessor-version":[{"id":20882,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20880\/revisions\/20882"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/20881"}],"wp:attachment":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=20880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=20880"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=20880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}