{"id":20900,"date":"2023-05-26T15:35:57","date_gmt":"2023-05-26T18:35:57","guid":{"rendered":"http:\/\/www.sindipetroba.org.br\/2019\/?p=20900"},"modified":"2023-05-26T15:35:57","modified_gmt":"2023-05-26T18:35:57","slug":"antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06","status":"publish","type":"post","link":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/","title":{"rendered":"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06"},"content":{"rendered":"<p>A FUP e o Sindipetro Bahia conseguiram agendar para o dia 15\/06, o retorno do diretor de Processos industriais, Willian Fran\u00e7a, do Gerente Executivo de RH, Felipe Freitas e da Gerente de Rela\u00e7\u00f5es Sindicais, Antonieta Vieira \u00e0 Bahia para uma segunda reuni\u00e3o com os trabalhadores e trabalhadoras que eram lotados na Refinaria Landulpho Alves (RLAM).<\/p>\n<p>A reuni\u00e3o vai acontecer \u00e0s 9h em local que ser\u00e1 divulgado brevemente. No encontro, a estatal vai apresentar o encerramento do plano de pessoal da RLAM e as devolutivas aos pleitos realizados pelas entidades sindicais no encontro do dia 11\/04\/23.<\/p>\n<p>Entre os diversos questionamentos, os trabalhadores cobram apoio para quest\u00f5es de sa\u00fade mental, esclarecimentos sobre a situa\u00e7\u00e3o de cada um, orienta\u00e7\u00e3o sobre as propostas de mobilidade e sobre o futuro na empresa.<\/p>\n<p>A FUP j\u00e1 fez in\u00fameras cobran\u00e7as ao RH da Petrobr\u00e1s para que a Companhia resolva as quest\u00f5es desses trabalhadores, pois muitos est\u00e3o passando por sofrimento ps\u00edquico. H\u00e1 uma grande expectativa de que at\u00e9 o dia da reuni\u00e3o, a diretoria executiva da Petrobr\u00e1s j\u00e1 tenha deliberado sobre os diversos temas que afligem esse segmento da categoria e possa trazer novidades positivas para o encontro com os trabalhadores.<\/p>\n<p>\u201cA diretoria executiva da Petrobr\u00e1s est\u00e1 prestes a aprovar uma s\u00e9rie de propostas que foram feitas pela FUP e seus sindicatos nas reuni\u00f5es, principalmente no Grupo de Trabalho (GT) de efetivo e transfer\u00eancia, e estamos nessa expectativa\u201d, ressalta o coordenador da Federa\u00e7\u00e3o, Deyvid Bacelar.<\/p>\n<p>A expectativa \u00e9 que a diretoria da Petrobr\u00e1s traga not\u00edcias positivas j\u00e1 com delibera\u00e7\u00f5es com solu\u00e7\u00f5es para as pessoas que est\u00e3o, por exemplo, fazendo bate volta para o Rio de Janeiro e outros estados para cumprir o presencial do coworking em im\u00f3veis fora da Bahia. A cobran\u00e7a feita pelas entidades sindicais para a Petrobr\u00e1s \u00e9 para que os trabalhadores possam cumprir a obriga\u00e7\u00e3o do trabalho presencial em um coworking ou im\u00f3vel da Petrobr\u00e1s pr\u00f3ximo ao seu local de origem. No caso da Bahia, atualmente esta etapa do trabalho \u00e9 feita no Suarez Trade, mas em breve, esperamos que passe a ser feita no edif\u00edcio Torre Pituba.<\/p>\n<p>Esperamos boas not\u00edcias tamb\u00e9m para que as pessoas com casos cr\u00edticos de sa\u00fade mental e f\u00edsica possam executar o teletrabalho 100%, pelo menos durante o tratamento. E ainda para as transfer\u00eancias que foram solicitadas (esperamos que j\u00e1 tenham sido realizadas) e em rela\u00e7\u00e3o \u00e0s 100 vagas na opera\u00e7\u00e3o pleiteadas na UN-BA.<\/p>\n<p>A reuni\u00e3o \u00e9 uma grande oportunidade para tirar d\u00favidas e fazer cobran\u00e7as, portanto, se voc\u00ea estiver em Salvador, n\u00e3o deixe de participar. \u00c9 importante mostrar a nossa mobiliza\u00e7\u00e3o e indigna\u00e7\u00e3o, pressionando para que nesse dia tenhamos boas novas.<\/p>\n<p>As entidades sindicais \u2013 FUP e Sindipetro- Ba \u2013 continuam pressionando e fazendo cobran\u00e7as, inclusive atrav\u00e9s de deputados e senadores, para que pressionem a Petrobr\u00e1s a esclarecer sobre o esquema de mobilidade e apresentar propostas de oportunidades para aqueles petroleiros que desejam permanecer na Bahia.<\/p>\n<p><em><strong>Fonte \u2013 Imprensa Sindipetro Bahia<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"A FUP e o Sindipetro Bahia conseguiram agendar para o dia 15\/06, o retorno do diretor de Processos industriais, Willian Fran\u00e7a, do Gerente Executivo de RH, Felipe Freitas e da Gerente de Rela\u00e7\u00f5es Sindicais, Antonieta Vieira \u00e0 Bahia para uma segunda reuni\u00e3o com os trabalhadores e trabalhadoras que eram lotados na Refinaria Landulpho Alves (RLAM)&#8230;. <a class=\"view-article\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/\">Ver artigo<\/a>","protected":false},"author":4,"featured_media":20901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-20900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06 - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06 - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"A FUP e o Sindipetro Bahia conseguiram agendar para o dia 15\/06, o retorno do diretor de Processos industriais, Willian Fran\u00e7a, do Gerente Executivo de RH, Felipe Freitas e da Gerente de Rela\u00e7\u00f5es Sindicais, Antonieta Vieira \u00e0 Bahia para uma segunda reuni\u00e3o com os trabalhadores e trabalhadoras que eram lotados na Refinaria Landulpho Alves (RLAM).... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-26T18:35:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/\"},\"author\":{\"name\":\"ASCOM\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\"},\"headline\":\"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\\\/06\",\"datePublished\":\"2023-05-26T18:35:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/\"},\"wordCount\":539,\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg\",\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/\",\"name\":\"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\\\/06 - Sindipetro BA\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg\",\"datePublished\":\"2023-05-26T18:35:57+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg\",\"width\":1200,\"height\":754},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\\\/06\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\",\"name\":\"ASCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"caption\":\"ASCOM\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06 - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/","og_locale":"pt_BR","og_type":"article","og_title":"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06 - Sindipetro BA","og_description":"A FUP e o Sindipetro Bahia conseguiram agendar para o dia 15\/06, o retorno do diretor de Processos industriais, Willian Fran\u00e7a, do Gerente Executivo de RH, Felipe Freitas e da Gerente de Rela\u00e7\u00f5es Sindicais, Antonieta Vieira \u00e0 Bahia para uma segunda reuni\u00e3o com os trabalhadores e trabalhadoras que eram lotados na Refinaria Landulpho Alves (RLAM).... Ver artigo","og_url":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2023-05-26T18:35:57+00:00","og_image":[{"width":1200,"height":754,"url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg","type":"image\/jpeg"}],"author":"ASCOM","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#article","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/"},"author":{"name":"ASCOM","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c"},"headline":"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06","datePublished":"2023-05-26T18:35:57+00:00","mainEntityOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/"},"wordCount":539,"publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg","articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/","name":"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06 - Sindipetro BA","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#primaryimage"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg","datePublished":"2023-05-26T18:35:57+00:00","breadcrumb":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#primaryimage","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-15.03.16.jpeg","width":1200,"height":754},{"@type":"BreadcrumbList","@id":"http:\/\/www.sindipetroba.org.br\/2019\/antigos-trabalhadores-da-rlam-esperam-respostas-da-direcao-da-petrobras-em-reuniao-marcada-para-o-dia-15-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Antigos trabalhadores da RLAM esperam respostas da dire\u00e7\u00e3o da Petrobr\u00e1s em reuni\u00e3o marcada para o dia 15\/06"}]},{"@type":"WebSite","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website","url":"http:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"http:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c","name":"ASCOM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","caption":"ASCOM"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=20900"}],"version-history":[{"count":1,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20900\/revisions"}],"predecessor-version":[{"id":20902,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/20900\/revisions\/20902"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/20901"}],"wp:attachment":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=20900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=20900"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=20900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}