{"id":21065,"date":"2023-06-14T14:54:20","date_gmt":"2023-06-14T17:54:20","guid":{"rendered":"http:\/\/www.sindipetroba.org.br\/2019\/?p=21065"},"modified":"2023-06-14T19:17:51","modified_gmt":"2023-06-14T22:17:51","slug":"trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act","status":"publish","type":"post","link":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/","title":{"rendered":"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT"},"content":{"rendered":"<p>O Sindipetro-Ba convoca os trabalhadores da SNA para participar de uma assembleia na pr\u00f3xima segunda-feira, 19\/06, \u00e0s 7h, na sede da empresa, em Pojuca, para discutir o Acordo Coletivo de Trabalho (ACT) 2022\/2023.<\/p>\n<p>Esse \u00e9 o primeiro ACT destes trabalhadores que passaram a ser representados pelo Sindipetro. A SNA presta servi\u00e7os para a Maha Energy, operando e dando manuten\u00e7\u00e3o nos campos de petr\u00f3leo no Rec\u00f4ncavo baiano.<\/p>\n<p>O Sindipetro j\u00e1 vem negociando h\u00e1 algum tempo com a SNA na tentativa de fechar esse primeiro acordo, garantir a representa\u00e7\u00e3o sindical e os direitos dos trabalhadores.<\/p>\n","protected":false},"excerpt":{"rendered":"O Sindipetro-Ba convoca os trabalhadores da SNA para participar de uma assembleia na pr\u00f3xima segunda-feira, 19\/06, \u00e0s 7h, na sede da empresa, em Pojuca, para discutir o Acordo Coletivo de Trabalho (ACT) 2022\/2023. Esse \u00e9 o primeiro ACT destes trabalhadores que passaram a ser representados pelo Sindipetro. A SNA presta servi\u00e7os para a Maha Energy,&#8230; <a class=\"view-article\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/\">Ver artigo<\/a>","protected":false},"author":4,"featured_media":21066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-21065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"O Sindipetro-Ba convoca os trabalhadores da SNA para participar de uma assembleia na pr\u00f3xima segunda-feira, 19\/06, \u00e0s 7h, na sede da empresa, em Pojuca, para discutir o Acordo Coletivo de Trabalho (ACT) 2022\/2023. Esse \u00e9 o primeiro ACT destes trabalhadores que passaram a ser representados pelo Sindipetro. A SNA presta servi\u00e7os para a Maha Energy,... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-14T17:54:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T22:17:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/\"},\"author\":{\"name\":\"ASCOM\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\"},\"headline\":\"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT\",\"datePublished\":\"2023-06-14T17:54:20+00:00\",\"dateModified\":\"2023-06-14T22:17:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/\"},\"wordCount\":111,\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg\",\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/\",\"name\":\"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT - Sindipetro BA\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg\",\"datePublished\":\"2023-06-14T17:54:20+00:00\",\"dateModified\":\"2023-06-14T22:17:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\",\"name\":\"ASCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"caption\":\"ASCOM\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/","og_locale":"pt_BR","og_type":"article","og_title":"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT - Sindipetro BA","og_description":"O Sindipetro-Ba convoca os trabalhadores da SNA para participar de uma assembleia na pr\u00f3xima segunda-feira, 19\/06, \u00e0s 7h, na sede da empresa, em Pojuca, para discutir o Acordo Coletivo de Trabalho (ACT) 2022\/2023. Esse \u00e9 o primeiro ACT destes trabalhadores que passaram a ser representados pelo Sindipetro. A SNA presta servi\u00e7os para a Maha Energy,... Ver artigo","og_url":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2023-06-14T17:54:20+00:00","article_modified_time":"2023-06-14T22:17:51+00:00","og_image":[{"width":1200,"height":1200,"url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg","type":"image\/jpeg"}],"author":"ASCOM","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#article","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/"},"author":{"name":"ASCOM","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c"},"headline":"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT","datePublished":"2023-06-14T17:54:20+00:00","dateModified":"2023-06-14T22:17:51+00:00","mainEntityOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/"},"wordCount":111,"publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg","articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/","name":"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT - Sindipetro BA","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#primaryimage"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg","datePublished":"2023-06-14T17:54:20+00:00","dateModified":"2023-06-14T22:17:51+00:00","breadcrumb":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#primaryimage","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-14.50.46.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"http:\/\/www.sindipetroba.org.br\/2019\/trabalhadores-da-empresa-sna-participam-de-assembleia-na-segunda-19-para-tratar-sobre-o-1-act\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Trabalhadores da empresa SNA participam de assembleia, na segunda (19), para tratar sobre o primeiro ACT"}]},{"@type":"WebSite","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website","url":"http:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"http:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c","name":"ASCOM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","caption":"ASCOM"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/21065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=21065"}],"version-history":[{"count":2,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/21065\/revisions"}],"predecessor-version":[{"id":21072,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/21065\/revisions\/21072"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/21066"}],"wp:attachment":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=21065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=21065"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=21065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}