{"id":21935,"date":"2023-08-21T14:23:10","date_gmt":"2023-08-21T17:23:10","guid":{"rendered":"http:\/\/www.sindipetroba.org.br\/2019\/?p=21935"},"modified":"2023-08-23T14:52:30","modified_gmt":"2023-08-23T17:52:30","slug":"sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador","status":"publish","type":"post","link":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/","title":{"rendered":"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador"},"content":{"rendered":"<p>Os abusivos descontos dos equacionamentos da Petros seguem assombrando a categoria petroleira. E, por isso, o Sindipetro-Ba realiza um novo ato unificado e convoca petroleiras e petroleiros a participarem da manifesta\u00e7\u00e3o para cobrar um posicionamento da Petrobr\u00e1s.<\/p>\n<p>A manifesta\u00e7\u00e3o est\u00e1 marcada para esta quarta-feira, 23 de agosto, a partir das 8h, em frente ao edif\u00edcio Torre Pituba, onde funciona o pr\u00e9dio administrativo da estatal, no bairro do Itaigara, em Salvador.<\/p>\n<p>Com os equacionamentos, aposentados e pensionistas t\u00eam sofrido grande impacto no or\u00e7amento, na sa\u00fade e na qualidade de vida, uma situa\u00e7\u00e3o grave e inadmiss\u00edvel.<\/p>\n<p>Caravanas sa\u00eddas do interior do estado j\u00e1 est\u00e3o preparadas para participar. A expectativa \u00e9 de que esse seja um ato ainda maior do que o ocorrido em 30 de maio.<\/p>\n<p>Agende-se:<br \/>\nO que?: Ato Unificado pelo fim dos equacionamentos da Petros<br \/>\nLocal: Sede administrativa da Petrobr\u00e1s em Salvador (Edif\u00edcio Torre Pituba, Av. Ant\u00f4nio Carlos Magalh\u00e3es, 1113 \u2013 Itaigara)<br \/>\nData: 23 de agosto (quarta-feira)<br \/>\nHora: 8h<\/p>\n","protected":false},"excerpt":{"rendered":"Os abusivos descontos dos equacionamentos da Petros seguem assombrando a categoria petroleira. E, por isso, o Sindipetro-Ba realiza um novo ato unificado e convoca petroleiras e petroleiros a participarem da manifesta\u00e7\u00e3o para cobrar um posicionamento da Petrobr\u00e1s. A manifesta\u00e7\u00e3o est\u00e1 marcada para esta quarta-feira, 23 de agosto, a partir das 8h, em frente ao edif\u00edcio&#8230; <a class=\"view-article\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/\">Ver artigo<\/a>","protected":false},"author":7,"featured_media":21936,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[2453,2787,2786],"class_list":["post-21935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-edificio-torre-pituba","tag-equacionamentos-da-petros","tag-manifestacao-pelo-fim-dos-equacionamentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"Os abusivos descontos dos equacionamentos da Petros seguem assombrando a categoria petroleira. E, por isso, o Sindipetro-Ba realiza um novo ato unificado e convoca petroleiras e petroleiros a participarem da manifesta\u00e7\u00e3o para cobrar um posicionamento da Petrobr\u00e1s. A manifesta\u00e7\u00e3o est\u00e1 marcada para esta quarta-feira, 23 de agosto, a partir das 8h, em frente ao edif\u00edcio... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-21T17:23:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-23T17:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM AL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM AL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/\"},\"author\":{\"name\":\"ASCOM AL\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/b34be57a1332ab60188a340a09275241\"},\"headline\":\"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador\",\"datePublished\":\"2023-08-21T17:23:10+00:00\",\"dateModified\":\"2023-08-23T17:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/\"},\"wordCount\":183,\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg\",\"keywords\":[\"Edif\u00edcio Torre Pituba\",\"equacionamentos da Petros\",\"manifesta\u00e7\u00e3o pelo fim dos equacionamentos\"],\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/\",\"name\":\"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador - Sindipetro BA\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg\",\"datePublished\":\"2023-08-21T17:23:10+00:00\",\"dateModified\":\"2023-08-23T17:52:30+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/b34be57a1332ab60188a340a09275241\",\"name\":\"ASCOM AL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7faf4b5e74f0ebf515009a1f27466f1b1ace10867d066a91562e822c805d3157?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7faf4b5e74f0ebf515009a1f27466f1b1ace10867d066a91562e822c805d3157?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7faf4b5e74f0ebf515009a1f27466f1b1ace10867d066a91562e822c805d3157?s=96&d=mm&r=g\",\"caption\":\"ASCOM AL\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/","og_locale":"pt_BR","og_type":"article","og_title":"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador - Sindipetro BA","og_description":"Os abusivos descontos dos equacionamentos da Petros seguem assombrando a categoria petroleira. E, por isso, o Sindipetro-Ba realiza um novo ato unificado e convoca petroleiras e petroleiros a participarem da manifesta\u00e7\u00e3o para cobrar um posicionamento da Petrobr\u00e1s. A manifesta\u00e7\u00e3o est\u00e1 marcada para esta quarta-feira, 23 de agosto, a partir das 8h, em frente ao edif\u00edcio... Ver artigo","og_url":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2023-08-21T17:23:10+00:00","article_modified_time":"2023-08-23T17:52:30+00:00","og_image":[{"width":1200,"height":1200,"url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg","type":"image\/jpeg"}],"author":"ASCOM AL","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM AL","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#article","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/"},"author":{"name":"ASCOM AL","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/b34be57a1332ab60188a340a09275241"},"headline":"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador","datePublished":"2023-08-21T17:23:10+00:00","dateModified":"2023-08-23T17:52:30+00:00","mainEntityOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/"},"wordCount":183,"publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg","keywords":["Edif\u00edcio Torre Pituba","equacionamentos da Petros","manifesta\u00e7\u00e3o pelo fim dos equacionamentos"],"articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/","name":"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador - Sindipetro BA","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#primaryimage"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg","datePublished":"2023-08-21T17:23:10+00:00","dateModified":"2023-08-23T17:52:30+00:00","breadcrumb":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#primaryimage","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.41.32.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-convoca-categoria-para-manifestacao-pelo-fim-dos-equacionamentos-nesta-quarta-feira-23-em-salvador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Sindipetro-Ba convoca categoria para manifesta\u00e7\u00e3o pelo fim dos equacionamentos nesta quarta-feira (23) em Salvador"}]},{"@type":"WebSite","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website","url":"http:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"http:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/b34be57a1332ab60188a340a09275241","name":"ASCOM AL","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7faf4b5e74f0ebf515009a1f27466f1b1ace10867d066a91562e822c805d3157?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7faf4b5e74f0ebf515009a1f27466f1b1ace10867d066a91562e822c805d3157?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7faf4b5e74f0ebf515009a1f27466f1b1ace10867d066a91562e822c805d3157?s=96&d=mm&r=g","caption":"ASCOM AL"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/21935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=21935"}],"version-history":[{"count":2,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/21935\/revisions"}],"predecessor-version":[{"id":21943,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/21935\/revisions\/21943"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/21936"}],"wp:attachment":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=21935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=21935"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=21935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}