{"id":22515,"date":"2023-10-25T16:08:56","date_gmt":"2023-10-25T19:08:56","guid":{"rendered":"http:\/\/www.sindipetroba.org.br\/2019\/?p=22515"},"modified":"2023-10-26T11:20:58","modified_gmt":"2023-10-26T14:20:58","slug":"sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen","status":"publish","type":"post","link":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/","title":{"rendered":"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen"},"content":{"rendered":"<p>A dire\u00e7\u00e3o do <strong>Sindipetro-Ba<\/strong> realizar\u00e1 uma nova rodada de negocia\u00e7\u00e3o com a dire\u00e7\u00e3o da Acelen, com o objetivo de fechar o Acordo Coletivo de Trabalho 2023\/2024. A entidade sindical espera que essa etapa resulte em avan\u00e7os significativos que valorizem e atendam \u00e0s demandas dos trabalhadores e trabalhadoras da companhia.<\/p>\n<p>A reuni\u00e3o, originalmente agendada para esta quinta-feira (26), foi remarcada a pedido da empresa. Sendo assim, o Sindipetro-Ba ir\u00e1 se reunir na ter\u00e7a-feira (31) pela manh\u00e3 para discutir as propostas apresentadas.<\/p>\n<p><strong>LINHA DO TEMPO DA NEGOCIA\u00c7\u00c3O<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><em><strong>9 de outubro<\/strong><\/em><\/span><\/p>\n<p>O Sindicato se reuniu com a empresa no dia 9 de outubro e mostrou insatisfa\u00e7\u00e3o pela falta de avan\u00e7os significativos nas negocia\u00e7\u00f5es do ACT. Nesse momento, a empresa havia apresentado uma contraproposta rebaixada e disse que iria apresentar melhoria nos itens na nova rodada de negocia\u00e7\u00e3o agendada inicialmente para o dia 26\/10.<\/p>\n<p>Foi prometido pela empresa a apresenta\u00e7\u00e3o de melhorias nos itens relacionados aos benef\u00edcios, que foram propostos na pauta de reivindica\u00e7\u00f5es dos trabalhadores entregue pelo Sindipetro.<br \/>\nNa oportunidade, a Acelen tamb\u00e9m se comprometeu a prorrogar o ACT at\u00e9 o dia 31\/10.<\/p>\n<p><span style=\"color: #ff0000;\"><strong><em>31 de agosto<\/em><\/strong><\/span><\/p>\n<p>Atendendo \u00e0 solicita\u00e7\u00e3o do Sindipetro Bahia, a Acelen prorrogou a validade do Acordo Coletivo de Trabalho (ACT) 2022\/2023 at\u00e9 o dia 30 de setembro, uma vez que as negocia\u00e7\u00f5es entre as partes ainda estavam em andamento.<\/p>\n<p><em><strong><span style=\"color: #ff0000;\">25 de agosto<\/span><\/strong><\/em><\/p>\n<p>Empresa apresentou uma contraproposta rebaixada. O Sindipetro recusou e defendeu que a companhia seguisse a pauta de reivindica\u00e7\u00f5es constru\u00edda em assembleia pelos (as) trabalhadores (as) e ressaltou a import\u00e2ncia de valorizar os empregados, que s\u00e3o os respons\u00e1veis diretos pelos lucros da empresa.<\/p>\n<p><span style=\"color: #ff0000;\"><em><strong>1\u00ba de agosto<\/strong><\/em><\/span><\/p>\n<p>A pauta de reivindica\u00e7\u00f5es foi protocolada pelo Sindipetro Bahia, no dia 1\u00ba de agosto, com solicita\u00e7\u00e3o para que fosse dado in\u00edcio imediato ao processo de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) 2023\/2024.<\/p>\n","protected":false},"excerpt":{"rendered":"A dire\u00e7\u00e3o do Sindipetro-Ba realizar\u00e1 uma nova rodada de negocia\u00e7\u00e3o com a dire\u00e7\u00e3o da Acelen, com o objetivo de fechar o Acordo Coletivo de Trabalho 2023\/2024. A entidade sindical espera que essa etapa resulte em avan\u00e7os significativos que valorizem e atendam \u00e0s demandas dos trabalhadores e trabalhadoras da companhia. A reuni\u00e3o, originalmente agendada para esta&#8230; <a class=\"view-article\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/\">Ver artigo<\/a>","protected":false},"author":4,"featured_media":22518,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2688,1],"tags":[],"class_list":["post-22515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banner-principal","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"A dire\u00e7\u00e3o do Sindipetro-Ba realizar\u00e1 uma nova rodada de negocia\u00e7\u00e3o com a dire\u00e7\u00e3o da Acelen, com o objetivo de fechar o Acordo Coletivo de Trabalho 2023\/2024. A entidade sindical espera que essa etapa resulte em avan\u00e7os significativos que valorizem e atendam \u00e0s demandas dos trabalhadores e trabalhadoras da companhia. A reuni\u00e3o, originalmente agendada para esta... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-25T19:08:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T14:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/10\/MATERIA-T-4-700x700.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ASCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/\"},\"author\":{\"name\":\"ASCOM\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\"},\"headline\":\"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen\",\"datePublished\":\"2023-10-25T19:08:56+00:00\",\"dateModified\":\"2023-10-26T14:20:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/\"},\"wordCount\":327,\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MATERIA-T-4.png\",\"articleSection\":[\"Banner Principal\",\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/\",\"name\":\"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen - Sindipetro BA\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MATERIA-T-4.png\",\"datePublished\":\"2023-10-25T19:08:56+00:00\",\"dateModified\":\"2023-10-26T14:20:58+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MATERIA-T-4.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/MATERIA-T-4.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\",\"name\":\"ASCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"caption\":\"ASCOM\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/","og_locale":"pt_BR","og_type":"article","og_title":"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen - Sindipetro BA","og_description":"A dire\u00e7\u00e3o do Sindipetro-Ba realizar\u00e1 uma nova rodada de negocia\u00e7\u00e3o com a dire\u00e7\u00e3o da Acelen, com o objetivo de fechar o Acordo Coletivo de Trabalho 2023\/2024. A entidade sindical espera que essa etapa resulte em avan\u00e7os significativos que valorizem e atendam \u00e0s demandas dos trabalhadores e trabalhadoras da companhia. A reuni\u00e3o, originalmente agendada para esta... Ver artigo","og_url":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2023-10-25T19:08:56+00:00","article_modified_time":"2023-10-26T14:20:58+00:00","og_image":[{"width":700,"height":700,"url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/10\/MATERIA-T-4-700x700.png","type":"image\/png"}],"author":"ASCOM","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#article","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/"},"author":{"name":"ASCOM","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c"},"headline":"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen","datePublished":"2023-10-25T19:08:56+00:00","dateModified":"2023-10-26T14:20:58+00:00","mainEntityOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/"},"wordCount":327,"publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/10\/MATERIA-T-4.png","articleSection":["Banner Principal","Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/","name":"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen - Sindipetro BA","isPartOf":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#primaryimage"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/10\/MATERIA-T-4.png","datePublished":"2023-10-25T19:08:56+00:00","dateModified":"2023-10-26T14:20:58+00:00","breadcrumb":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#primaryimage","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/10\/MATERIA-T-4.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2023\/10\/MATERIA-T-4.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"http:\/\/www.sindipetroba.org.br\/2019\/sindipetro-ba-realiza-nova-rodada-de-negociacao-do-acordo-coletivo-de-trabalho-act-com-acelen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Sindipetro-Ba realiza nova rodada de negocia\u00e7\u00e3o do Acordo Coletivo de Trabalho (ACT) com a Acelen"}]},{"@type":"WebSite","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#website","url":"http:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"http:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"http:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"http:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c","name":"ASCOM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","caption":"ASCOM"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/22515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=22515"}],"version-history":[{"count":1,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/22515\/revisions"}],"predecessor-version":[{"id":22517,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/22515\/revisions\/22517"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/22518"}],"wp:attachment":[{"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=22515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=22515"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=22515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}