{"id":13582,"date":"2021-06-10T10:29:08","date_gmt":"2021-06-10T13:29:08","guid":{"rendered":"https:\/\/www.sindipetroba.org.br\/2019\/?p=13582"},"modified":"2021-06-10T10:29:08","modified_gmt":"2021-06-10T13:29:08","slug":"fup-e-cartacapital-unem-se-na-defesa-da-petrobras","status":"publish","type":"post","link":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/","title":{"rendered":"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s"},"content":{"rendered":"<div class=\"itemImageBlock\"><span class=\"itemImage\"> <a title=\"Clique para imagem de visualiza\u00e7\u00e3o\" href=\"https:\/\/fup.org.br\/media\/k2\/items\/cache\/23d7a632e10421b14aa13521ee01018a_XL.jpg?t=20210608_202756\" data-k2-modal=\"image\"> <img decoding=\"async\" src=\"https:\/\/fup.org.br\/media\/k2\/items\/cache\/23d7a632e10421b14aa13521ee01018a_L.jpg?t=20210608_202756\" alt=\"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s\" \/> <\/a> <\/span><\/p>\n<div class=\"clr\"><\/div>\n<\/div>\n<div class=\"itemFullText\">\n<div class=\"addtoany_container\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"itemFullText\">\n<p><strong><em>Assinando a revista Carta Capital, petroleiros e petroleiras e a sociedade em geral, podem ajudar \u00e0 Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) na luta em defesa da Petrobr\u00e1s p\u00fablica.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Neste momento em que a Petrobras sofre o maior desmonte da sua hist\u00f3ria, com a empresa sendo privatizada aos peda\u00e7os, \u00e9 fundamental contarmos com um jornalismo destemido, cr\u00edtico e comprometido com os interesses do povo brasileiro. \u00c9 com essa premissa que CartaCapital e a Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) se unem nesta campanha. Nosso projeto visa oferecer semanalmente o jornalismo tradicionalmente combativo e honesto da revista a pre\u00e7os acess\u00edveis para os petroleiros e demais trabalhadores brasileiros. Parte dos valores pagos na assinatura de CartaCapital ser\u00e1 revertida para a FUP, para que ela continue sua luta contra as privatiza\u00e7\u00f5es e o desmonte da maior estatal brasileira. Assim, ao mesmo tempo que o jornalismo independente de CartaCapital mant\u00e9m seu p\u00fablico informado, a partir da leitura clara, cr\u00edtica e transparente dos acontecimentos mais significativos da atualidade, com colunistas plurais e um conte\u00fado rico e criativo, voc\u00ea tamb\u00e9m participa apoiando diretamente a FUP em sua luta em defesa da soberania nacional.<\/p>\n<h3><strong>Para acessar ao benef\u00edcio e assinar a revista, clique no seguinte link:<\/strong>\u00a0<a href=\"https:\/\/bit.ly\/34XhJjw\">https:\/\/bit.ly\/34XhJjw<\/a><\/h3>\n<p>&nbsp;<\/p>\n<p><em>*Leia a \u00edntegra do manifesto da campanha:<\/em><\/p>\n<p>Desde a campanha O Petr\u00f3leo \u00c9 Nosso, que resultou na cria\u00e7\u00e3o da Petrobras em 1953, a luta para que o Pa\u00eds mantenha o controle sobre esse recurso t\u00e3o precioso e estrat\u00e9gico vem atravessando v\u00e1rias gera\u00e7\u00f5es de brasileiros. \u00c9 o que chamamos de defesa da soberania nacional, um esfor\u00e7o que marcou a hist\u00f3ria da na\u00e7\u00e3o ao longo de todas essas d\u00e9cadas, mas que os principais ve\u00edculos da imprensa brasileira sempre boicotaram ou tentaram desqualificar. Foi assim nos anos 1990, quando a m\u00eddia apoiou abertamente a quebra do monop\u00f3lio da Petrobras e o in\u00edcio do desmonte e da desnacionaliza\u00e7\u00e3o da empresa, defendendo o fechamento e a privatiza\u00e7\u00e3o de subsidi\u00e1rias, as parcerias privadas e a venda de a\u00e7\u00f5es da empresa na Bolsa de Nova York.<\/p>\n<p>Nos anos 2000, a chamada \u201cgrande imprensa\u201d boicotou o fortalecimento da Petrobras e a pol\u00edtica de conte\u00fado nacional, duvidou das potencialidades do pr\u00e9-sal e colocou em xeque sua capacidade de explorar as maiores jazidas descobertas nesta \u00faltima d\u00e9cada. Durante a Opera\u00e7\u00e3o Lava Jato, nem se fala. Os principais ve\u00edculos da m\u00eddia comercial foram parceiros da campanha promovida pelo ent\u00e3o juiz Sergio Moro, que resultou no desmonte da cadeia produtiva de \u00f3leo e g\u00e1s do Pa\u00eds, que quase destruiu a Petrobras e provocou a maior desindustrializa\u00e7\u00e3o da nossa hist\u00f3ria, cujos efeitos ser\u00e3o sentidos por d\u00e9cadas. Hoje sabemos onde tudo isso desaguou.<\/p>\n<p>O golpe de 2016 e a elei\u00e7\u00e3o de um governo de extrema-direita, gestado no \u00f3dio que a m\u00eddia alimentou, tiveram consequ\u00eancias devastadoras para o povo brasileiro, fragilizaram a democracia e as institui\u00e7\u00f5es nacionais. A imprensa tradicional foi coautora desse enredo. Muitos dos jornalistas que hoje confrontam o governo Bolsonaro, quando n\u00e3o foram coniventes com a campanha s\u00f3rdida da Lava Jato, recusaram-se a apurar e investigar os fatos com imparcialidade e compromisso com a verdade factual, princ\u00edpios fundamentais do of\u00edcio. Se podemos tirar uma li\u00e7\u00e3o de tudo isso, esta \u00e9 a necessidade de termos uma m\u00eddia livre, independente, comprometida com o Estado Democr\u00e1tico de Direito e com a defesa da soberania nacional. CartaCapital sempre se pautou por esses valores e foi uma das raras exce\u00e7\u00f5es na cobertura dos fatos que marcaram a hist\u00f3ria recente do Pa\u00eds, questionando e denunciando os ataques contra a democracia e os interesses nacionais.<\/p>\n<p>Neste momento em que a Petrobras sofre o maior desmonte da sua hist\u00f3ria, com a empresa sendo privatizada aos peda\u00e7os, \u00e9 fundamental contarmos com um jornalismo destemido, cr\u00edtico e comprometido com os interesses do povo brasileiro. \u00c9 com essa premissa que CartaCapital e a Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) se unem nesta campanha juntamente com VOC\u00ca, petroleiro e petroleira, por meio de assinaturas, em prol de uma cobertura cr\u00edtica da realidade brasileira. Nosso projeto visa oferecer semanalmente o jornalismo tradicionalmente combativo e honesto da revista a pre\u00e7os acess\u00edveis para os petroleiros e demais trabalhadores brasileiros. Parte dos valores pagos na assinatura de CartaCapital ser\u00e1 revertida para a FUP, para que ela continue sua luta contra as privatiza\u00e7\u00f5es e o desmonte da maior estatal brasileira. Assim, ao mesmo tempo que o jornalismo independente de CartaCapital mant\u00e9m seu p\u00fablico informado, a partir da leitura clara, cr\u00edtica e transparente dos acontecimentos mais significativos da atualidade, com colunistas plurais e um conte\u00fado rico e criativo, voc\u00ea tamb\u00e9m participa apoiando diretamente a FUP em sua luta em defesa da soberania nacional.<\/p>\n<p>Aproveite este convite, pois, juntos, faremos a nossa voz ecoar bem mais distante, em mais uma justa luta em favor da manuten\u00e7\u00e3o dos verdadeiros interesses nacionais. O petr\u00f3leo \u00e9 um bem muito importante e deve continuar sendo um dos principais ativos da pauta econ\u00f4mica brasileira.<\/p>\n<\/div>\n<div class=\"clr\"><\/div>\n<div class=\"itemContentFooter\"><span class=\"itemDateModified\"> \u00daltima modifica\u00e7\u00e3o em Ter\u00e7a, 08 Junho 2021 17:27 <\/span><\/p>\n<div class=\"clr\"><\/div>\n<\/div>\n<div class=\"w357-item-categories\">Publicado em <a href=\"https:\/\/fup.org.br\/ultimas-noticias\/itemlist\/category\/835-sistema-petrobras\">Sistema Petrobr\u00e1s<\/a><\/div>\n<div><\/div>\n<div>Via Site FUP<\/div>\n","protected":false},"excerpt":{"rendered":"&nbsp; Assinando a revista Carta Capital, petroleiros e petroleiras e a sociedade em geral, podem ajudar \u00e0 Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) na luta em defesa da Petrobr\u00e1s p\u00fablica. &nbsp; Neste momento em que a Petrobras sofre o maior desmonte da sua hist\u00f3ria, com a empresa sendo privatizada aos peda\u00e7os, \u00e9 fundamental contarmos com um&#8230; <a class=\"view-article\" href=\"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/\">Ver artigo<\/a>","protected":false},"author":5,"featured_media":13583,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Assinando a revista Carta Capital, petroleiros e petroleiras e a sociedade em geral, podem ajudar \u00e0 Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) na luta em defesa da Petrobr\u00e1s p\u00fablica. &nbsp; Neste momento em que a Petrobras sofre o maior desmonte da sua hist\u00f3ria, com a empresa sendo privatizada aos peda\u00e7os, \u00e9 fundamental contarmos com um... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-10T13:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2021\/06\/FUP-MATERIA-10061.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM LH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM LH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/\"},\"author\":{\"name\":\"ASCOM LH\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/72a6cd7d4c9df602b5b1d4f0ac95d3b5\"},\"headline\":\"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s\",\"datePublished\":\"2021-06-10T13:29:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/\"},\"wordCount\":891,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/FUP-MATERIA-10061.jpg\",\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/\",\"name\":\"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s - Sindipetro BA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/FUP-MATERIA-10061.jpg\",\"datePublished\":\"2021-06-10T13:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/FUP-MATERIA-10061.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/FUP-MATERIA-10061.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/72a6cd7d4c9df602b5b1d4f0ac95d3b5\",\"name\":\"ASCOM LH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d074b4cc54d766fa6795561991fa0f7c17b5f93fc3946b2fb84691e4e5fb9230?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d074b4cc54d766fa6795561991fa0f7c17b5f93fc3946b2fb84691e4e5fb9230?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d074b4cc54d766fa6795561991fa0f7c17b5f93fc3946b2fb84691e4e5fb9230?s=96&d=mm&r=g\",\"caption\":\"ASCOM LH\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/","og_locale":"pt_BR","og_type":"article","og_title":"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s - Sindipetro BA","og_description":"&nbsp; Assinando a revista Carta Capital, petroleiros e petroleiras e a sociedade em geral, podem ajudar \u00e0 Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) na luta em defesa da Petrobr\u00e1s p\u00fablica. &nbsp; Neste momento em que a Petrobras sofre o maior desmonte da sua hist\u00f3ria, com a empresa sendo privatizada aos peda\u00e7os, \u00e9 fundamental contarmos com um... Ver artigo","og_url":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2021-06-10T13:29:08+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2021\/06\/FUP-MATERIA-10061.jpg","type":"image\/jpeg"}],"author":"ASCOM LH","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM LH","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#article","isPartOf":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/"},"author":{"name":"ASCOM LH","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/72a6cd7d4c9df602b5b1d4f0ac95d3b5"},"headline":"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s","datePublished":"2021-06-10T13:29:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/"},"wordCount":891,"publisher":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2021\/06\/FUP-MATERIA-10061.jpg","articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/","url":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/","name":"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s - Sindipetro BA","isPartOf":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#primaryimage"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2021\/06\/FUP-MATERIA-10061.jpg","datePublished":"2021-06-10T13:29:08+00:00","breadcrumb":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#primaryimage","url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2021\/06\/FUP-MATERIA-10061.jpg","contentUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2021\/06\/FUP-MATERIA-10061.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindipetroba.org.br\/2019\/fup-e-cartacapital-unem-se-na-defesa-da-petrobras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"FUP e CartaCapital unem-se na defesa da Petrobr\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#website","url":"https:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"https:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/72a6cd7d4c9df602b5b1d4f0ac95d3b5","name":"ASCOM LH","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d074b4cc54d766fa6795561991fa0f7c17b5f93fc3946b2fb84691e4e5fb9230?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d074b4cc54d766fa6795561991fa0f7c17b5f93fc3946b2fb84691e4e5fb9230?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d074b4cc54d766fa6795561991fa0f7c17b5f93fc3946b2fb84691e4e5fb9230?s=96&d=mm&r=g","caption":"ASCOM LH"},"sameAs":["http:\/\/www.sindipetroba.org.br\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/13582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=13582"}],"version-history":[{"count":3,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/13582\/revisions"}],"predecessor-version":[{"id":13596,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/13582\/revisions\/13596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/13583"}],"wp:attachment":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=13582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=13582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=13582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}