{"id":28826,"date":"2026-01-30T23:33:38","date_gmt":"2026-01-31T02:33:38","guid":{"rendered":"https:\/\/www.sindipetroba.org.br\/2019\/?p=28826"},"modified":"2026-01-30T23:33:38","modified_gmt":"2026-01-31T02:33:38","slug":"semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba","status":"publish","type":"post","link":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/","title":{"rendered":"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA"},"content":{"rendered":"<p>O p\u00f4r do sol desta sexta-feira (30) marcou o fim da Semana dos Aposentados e das Aposentadas do Sindipetro Bahia, encerrando os cinco dias de atividades culturais e formativas que estimularam mem\u00f3rias e sentidos de petroleiros e petroleiras aposentados(as) e pensionistas. O formato inovador, com uma programa\u00e7\u00e3o que se repetia a cada dia para receber delega\u00e7\u00f5es vindas de diferentes regi\u00f5es do estado, foi aprovado por aqueles e aquelas que s\u00e3o a for\u00e7a da categoria petroleira.<\/p>\n<p>A coordenadora geral do Sindipetro-BA, Elizabete Sacramento, parabenizou aposentados(as) e pensionistas pela disposi\u00e7\u00e3o em participar das atividades. \u201cEstamos bem felizes que essa Semana foi abra\u00e7ada por quem chegou aqui. Nosso objetivo \u00e9 sempre diversificar e inovar, proporcionando experi\u00eancias variadas para nossos associados e associadas. Al\u00e9m da celebra\u00e7\u00e3o e da confraterniza\u00e7\u00e3o, vamos continuar valorizando momentos de forma\u00e7\u00e3o pol\u00edtica e cultural\u201d, afirmou.<\/p>\n<p>Ao modificar o formato deste ano, a diretoria do Sindipetro-BA mostrou estar sintonizada com a base: muitos participantes elogiaram o novo modelo. \u201cEstou adorando esse evento. E foi uma boa ideia fazer assim por etapas, porque abrange todo mundo\u201d, declarou a pensionista Vilma da Silva. \u201cFomos muito bem recebidos, com tudo que t\u00ednhamos direito, estou feliz da vida\u201d, disse a tamb\u00e9m pensionista Alice Leite, ap\u00f3s o almo\u00e7o no Ra\u00edzes do Brasil.<\/p>\n<p>Perante o sucesso desta edi\u00e7\u00e3o, o diretor de Seguridade do Sindipetro, Valnilton Cruz, revelou que a diretoria j\u00e1 come\u00e7ou a pensar no pr\u00f3ximo ano. \u201cEst\u00e3o surgindo algumas ideias, temos conversado sobre elas. E podem mandar as de voc\u00eas tamb\u00e9m\u201d, disse ele para a plateia de aposentados(as) e pensionistas.<\/p>\n<p>Se voc\u00ea tem alguma opini\u00e3o, impress\u00e3o ou sugest\u00e3o sobre a Semana dos Aposentados, envie para o PetroZap, atrav\u00e9s do n\u00famero (71) 99924-2999.<\/p>\n","protected":false},"excerpt":{"rendered":"O p\u00f4r do sol desta sexta-feira (30) marcou o fim da Semana dos Aposentados e das Aposentadas do Sindipetro Bahia, encerrando os cinco dias de atividades culturais e formativas que estimularam mem\u00f3rias e sentidos de petroleiros e petroleiras aposentados(as) e pensionistas. O formato inovador, com uma programa\u00e7\u00e3o que se repetia a cada dia para receber&#8230; <a class=\"view-article\" href=\"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/\">Ver artigo<\/a>","protected":false},"author":4,"featured_media":28822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2688,1],"tags":[],"class_list":["post-28826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banner-principal","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"O p\u00f4r do sol desta sexta-feira (30) marcou o fim da Semana dos Aposentados e das Aposentadas do Sindipetro Bahia, encerrando os cinco dias de atividades culturais e formativas que estimularam mem\u00f3rias e sentidos de petroleiros e petroleiras aposentados(as) e pensionistas. O formato inovador, com uma programa\u00e7\u00e3o que se repetia a cada dia para receber... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-31T02:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1186\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ASCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ASCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/\"},\"author\":{\"name\":\"ASCOM\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\"},\"headline\":\"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA\",\"datePublished\":\"2026-01-31T02:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg\",\"articleSection\":[\"Banner Principal\",\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/\",\"name\":\"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA - Sindipetro BA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg\",\"datePublished\":\"2026-01-31T02:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg\",\"width\":1186,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/80e88dbf823328ddad08b17600055a3c\",\"name\":\"ASCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g\",\"caption\":\"ASCOM\"},\"sameAs\":[\"http:\\\/\\\/www.sindipetroba.org.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/","og_locale":"pt_BR","og_type":"article","og_title":"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA - Sindipetro BA","og_description":"O p\u00f4r do sol desta sexta-feira (30) marcou o fim da Semana dos Aposentados e das Aposentadas do Sindipetro Bahia, encerrando os cinco dias de atividades culturais e formativas que estimularam mem\u00f3rias e sentidos de petroleiros e petroleiras aposentados(as) e pensionistas. O formato inovador, com uma programa\u00e7\u00e3o que se repetia a cada dia para receber... Ver artigo","og_url":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2026-01-31T02:33:38+00:00","og_image":[{"width":1186,"height":1280,"url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg","type":"image\/jpeg"}],"author":"ASCOM","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"ASCOM","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#article","isPartOf":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/"},"author":{"name":"ASCOM","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c"},"headline":"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA","datePublished":"2026-01-31T02:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/"},"wordCount":317,"publisher":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg","articleSection":["Banner Principal","Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/","url":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/","name":"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA - Sindipetro BA","isPartOf":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#primaryimage"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg","datePublished":"2026-01-31T02:33:38+00:00","breadcrumb":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#primaryimage","url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg","contentUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-30-at-23.31.06.jpeg","width":1186,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindipetroba.org.br\/2019\/semana-dos-aposentados-formato-inovador-agrada-associadosas-do-sindipetro-ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Semana dos Aposentados: formato inovador agrada associados(as) do Sindipetro-BA"}]},{"@type":"WebSite","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#website","url":"https:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"https:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/80e88dbf823328ddad08b17600055a3c","name":"ASCOM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ab2fd873c57926b9f03e30be8804429fd7b0d41f4f71170e45b7b7f84998a6?s=96&d=mm&r=g","caption":"ASCOM"},"sameAs":["http:\/\/www.sindipetroba.org.br"]}]}},"_links":{"self":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/28826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=28826"}],"version-history":[{"count":1,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/28826\/revisions"}],"predecessor-version":[{"id":28827,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/28826\/revisions\/28827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/28822"}],"wp:attachment":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=28826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=28826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=28826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}