{"id":3333,"date":"2019-08-30T15:48:47","date_gmt":"2019-08-30T18:48:47","guid":{"rendered":"https:\/\/www.sindipetroba.org.br\/2019\/?p=3333"},"modified":"2019-08-30T16:19:24","modified_gmt":"2019-08-30T19:19:24","slug":"vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve","status":"publish","type":"post","link":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/","title":{"rendered":"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve"},"content":{"rendered":"<p>A luta e a uni\u00e3o venceram o medo, dando uma vit\u00f3ria esmagadora para a categoria petroleira, FUP e Sindipetros, nas assembleias que deliberaram sobre a 3\u00aa contraproposta da Petrobr\u00e1s e os indicativos da Federa\u00e7\u00e3o.<\/p>\n<p>Na Bahia, 78% dos petroleiros rejeitaram a contraproposta da empresa, sendo que apenas 18% foram a favor e 4% se abstiveram.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 realiza\u00e7\u00e3o de uma greve no caso de ataques ao patrim\u00f4nio jur\u00eddico coletivo da categoria, durante o processo negocial, 75% foram \u00a0a favor, 21% contra e 4% se abstiveram.<\/p>\n<p>No caso do indicativo de manuten\u00e7\u00e3o da negocia\u00e7\u00e3o coletiva sobre os pontos divergentes, 84% foram a favor, 14% contra e 2% se abstiveram.<\/p>\n<p>No outro indicativo da FUP, de prorroga\u00e7\u00e3o dos efeitos do atual ACT, 84% votaram a favor, 14% contra e 2% se abstiveram.<\/p>\n<p>Na Bahia, como em outros estados, houve um forte aparato intimidador de gerentes da Petrobr\u00e1s, a mando da atual gest\u00e3o da estatal, que queria medir for\u00e7as com os sindicatos e obrigar a categoria, atrav\u00e9s de amea\u00e7a e ass\u00e9dio, a votar a favor de uma proposta prejudicial, com retirada de direitos.<\/p>\n<p>Foram assembleias at\u00edpicas como nunca foi visto na hist\u00f3ria da categoria petroleira, com participa\u00e7\u00e3o de \u00a0todos os gerentes gerais, em assembleias grandes como a do EDIBA e do adm da RLAM.<\/p>\n<p>A diretoria do Sindipetro deixou claro nas assembleias, que aconteceram de 21 a 30\/08, em todas as unidades da Petrobr\u00e1s na Bahia, que n\u00e3o h\u00e1 impedimento da presen\u00e7a dos gerentes e supervisores nas assembleias, desde que participem de livre e espont\u00e2nea vontade, o que n\u00e3o foi o caso.<\/p>\n<p>O fato \u00e9 que a estrat\u00e9gia assediadora, imposta pela alta gest\u00e3o da empresa foi um tiro no p\u00e9 e se mostrou ineficiente em face da consci\u00eancia e unidade dos trabalhadores petroleiros. Al\u00e9m de ter dado audi\u00eancia a atividade do sindicato e exposto os gerentes \u00e0 base.<\/p>\n<p>Diante da posi\u00e7\u00e3o da Petrobr\u00e1s de intervir e agir com coa\u00e7\u00e3o por seus interesses nas assembleias sindicais, o\u00a0 Sindipetro Bahia, atrav\u00e9s de sua assessoria jur\u00eddica, apresentou den\u00fancia a estatal no Minist\u00e9rio P\u00fablico do Trabalho sob n\u00ba NF 001909.2019.05.000\/6, que est\u00e1 em andamento.<\/p>\n<p>Preocupada com a amea\u00e7a de greve e percebendo a derrota iminente nas assembleias, a atual gest\u00e3o da Petrobr\u00e1s entrou com pedido de media\u00e7\u00e3o \u00a0do ACT no Tribunal Superior do Trabalho (TST).<\/p>\n<p>A media\u00e7\u00e3o aconteceu na quinta-feira (29), mas a dire\u00e7\u00e3o da estatal n\u00e3o aceitou a proposta das federa\u00e7\u00f5es de prorrogar o Acordo Coletivo e manter o processo \u00a0de discuss\u00e3o em mesa de negocia\u00e7\u00e3o, na pr\u00f3pria empresa.<\/p>\n<p>O ministro do TST tamb\u00e9m prop\u00f4s que a empresa prorrogue o ACT e d\u00ea continuidade \u00e0 media\u00e7\u00e3o no Tribunal. A Petrobras tem at\u00e9 \u00e0s 10h de segunda-feira (02\/09) para responder se aceita ou n\u00e3o a proposta.<\/p>\n<p>Para o coordenador do Sindipetro Bahia, Jairo Batista, \u201ca categoria, FUP e Sindipetros cumpriram o seu papel e sa\u00edram fortalecidos na luta contra a privatiza\u00e7\u00e3o do Sistema Petrobr\u00e1s e contra a retirada de direitos. O recado dado para a empresa \u00e9 que a chama da resist\u00eancia continua acesa\u201d .<\/p>\n<p>Clique nos links abaixo para ver os resultados das assembleias por indicativo e por base<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/Assembleias-de-21-a-30-MANUTEN\u00c7\u00c3O-DA-NEGOCIA\u00c7\u00c3O-COLETIVA-SOBRE-OS-PONTOS-DIVERGENTES.pdf\">Manuten\u00e7\u00e3o da negocia\u00e7\u00e3o coletiva sobre os pontos divergentes<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/Assembleias-de-21-a-30-Prorroga\u00e7\u00e3o-dos-efeitos-do-atual-acordo-coletivo-de-trabalho-enquanto-durarem-as-negocia\u00e7\u00f5es-demonstrando-boa-f\u00e9-negocial.pdf\">Prorroga\u00e7\u00e3o dos efeitos do atual acordo coletivo de trabalho enquanto durarem as negocia\u00e7\u00f5es, demonstrando boa f\u00e9 negocial<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/Assembleias-de-21-a-30-rejei\u00e7\u00e3o-proposta-valendo-mudan\u00e7a-2.pdf\">\u00a03\u00aa contraproposta da Petrobr\u00e1s<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/Assembleias-de-21-a-30-Aprova\u00e7\u00e3o-de-greve-em-data-a-ser-definida-pela-FUP-e-seus-sindicatos-no-caso-de-ataques-ao-patrim\u00f4nio-jur\u00eddico-coletivo-da-categoria-durante-o-processo-negocial.-1.pdf\">Aprova\u00e7\u00e3o de greve em data a ser definida pela FUP e seus sindicatos, no caso de ataques ao patrim\u00f4nio jur\u00eddico coletivo da categoria, durante o processo negocial<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0Clique aqui para ver a galeria de fotos das AGES\u00a0<\/strong><\/p>\n<p>Fonte- Sindipetro Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"A luta e a uni\u00e3o venceram o medo, dando uma vit\u00f3ria esmagadora para a categoria petroleira, FUP e Sindipetros, nas assembleias que deliberaram sobre a 3\u00aa contraproposta da Petrobr\u00e1s e os indicativos da Federa\u00e7\u00e3o. Na Bahia, 78% dos petroleiros rejeitaram a contraproposta da empresa, sendo que apenas 18% foram a favor e 4% se abstiveram&#8230;. <a class=\"view-article\" href=\"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/\">Ver artigo<\/a>","protected":false},"author":1,"featured_media":3208,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[249,70,139,292,30],"class_list":["post-3333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-age","tag-fup","tag-nenhum-direito-a-menos","tag-rejeicao-da-contraproposta-da-petrobras","tag-sindipetro-bahia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve - Sindipetro BA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve - Sindipetro BA\" \/>\n<meta property=\"og:description\" content=\"A luta e a uni\u00e3o venceram o medo, dando uma vit\u00f3ria esmagadora para a categoria petroleira, FUP e Sindipetros, nas assembleias que deliberaram sobre a 3\u00aa contraproposta da Petrobr\u00e1s e os indicativos da Federa\u00e7\u00e3o. Na Bahia, 78% dos petroleiros rejeitaram a contraproposta da empresa, sendo que apenas 18% foram a favor e 4% se abstiveram.... Ver artigo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindipetro BA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sindipetroBa\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T18:48:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-30T19:19:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/rlam-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admsp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:site\" content=\"@SindipetroBahia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admsp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/\"},\"author\":{\"name\":\"admsp\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/e61228ef9f981537d4c4eb80f6ea7713\"},\"headline\":\"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve\",\"datePublished\":\"2019-08-30T18:48:47+00:00\",\"dateModified\":\"2019-08-30T19:19:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/\"},\"wordCount\":638,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/rlam-2.jpg\",\"keywords\":[\"AGE\",\"FUP\",\"nenhum direito a menos\",\"rejei\u00e7\u00e3o da contraproposta da Petrobr\u00e1s\",\"sindipetro bahia\"],\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/\",\"name\":\"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve - Sindipetro BA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/rlam-2.jpg\",\"datePublished\":\"2019-08-30T18:48:47+00:00\",\"dateModified\":\"2019-08-30T19:19:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/rlam-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/rlam-2.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"name\":\"Sindipetro BA\",\"description\":\"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#organization\",\"name\":\"Sindipetro BA\",\"url\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"contentUrl\":\"http:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/sindipetro-marca-cor.png\",\"width\":350,\"height\":126,\"caption\":\"Sindipetro BA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sindipetroBa\\\/\",\"https:\\\/\\\/x.com\\\/SindipetroBahia\",\"https:\\\/\\\/www.instagram.com\\\/sindipetroba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SindipetroBahiaOficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindipetroba.org.br\\\/2019\\\/#\\\/schema\\\/person\\\/e61228ef9f981537d4c4eb80f6ea7713\",\"name\":\"admsp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50f06e2b746fe9248099d2c61c12342ab36327e9d413e3171dd7033b84800d96?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50f06e2b746fe9248099d2c61c12342ab36327e9d413e3171dd7033b84800d96?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50f06e2b746fe9248099d2c61c12342ab36327e9d413e3171dd7033b84800d96?s=96&d=mm&r=g\",\"caption\":\"admsp\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve - Sindipetro BA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/","og_locale":"pt_BR","og_type":"article","og_title":"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve - Sindipetro BA","og_description":"A luta e a uni\u00e3o venceram o medo, dando uma vit\u00f3ria esmagadora para a categoria petroleira, FUP e Sindipetros, nas assembleias que deliberaram sobre a 3\u00aa contraproposta da Petrobr\u00e1s e os indicativos da Federa\u00e7\u00e3o. Na Bahia, 78% dos petroleiros rejeitaram a contraproposta da empresa, sendo que apenas 18% foram a favor e 4% se abstiveram.... Ver artigo","og_url":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/","og_site_name":"Sindipetro BA","article_publisher":"https:\/\/www.facebook.com\/sindipetroBa\/","article_published_time":"2019-08-30T18:48:47+00:00","article_modified_time":"2019-08-30T19:19:24+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/rlam-2.jpg","type":"image\/jpeg"}],"author":"admsp","twitter_card":"summary_large_image","twitter_creator":"@SindipetroBahia","twitter_site":"@SindipetroBahia","twitter_misc":{"Escrito por":"admsp","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#article","isPartOf":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/"},"author":{"name":"admsp","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/e61228ef9f981537d4c4eb80f6ea7713"},"headline":"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve","datePublished":"2019-08-30T18:48:47+00:00","dateModified":"2019-08-30T19:19:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/"},"wordCount":638,"publisher":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/rlam-2.jpg","keywords":["AGE","FUP","nenhum direito a menos","rejei\u00e7\u00e3o da contraproposta da Petrobr\u00e1s","sindipetro bahia"],"articleSection":["Not\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/","url":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/","name":"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve - Sindipetro BA","isPartOf":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#primaryimage"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/rlam-2.jpg","datePublished":"2019-08-30T18:48:47+00:00","dateModified":"2019-08-30T19:19:24+00:00","breadcrumb":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#primaryimage","url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/rlam-2.jpg","contentUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/08\/rlam-2.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindipetroba.org.br\/2019\/vitoria-esmagadora-78-dos-petroleiros-da-bahia-rejeitam-contraproposta-da-petrobras-e-75-aprovam-greve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sindipetroba.org.br\/2019\/"},{"@type":"ListItem","position":2,"name":"Vit\u00f3ria esmagadora \u2013 78% dos petroleiros da Bahia rejeitam contraproposta da Petrobr\u00e1s e 75% aprovam greve"}]},{"@type":"WebSite","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#website","url":"https:\/\/www.sindipetroba.org.br\/2019\/","name":"Sindipetro BA","description":"Sindicato dos Petroleiros e Petroleiras do Estado da Bahia","publisher":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindipetroba.org.br\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#organization","name":"Sindipetro BA","url":"https:\/\/www.sindipetroba.org.br\/2019\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","contentUrl":"https:\/\/www.sindipetroba.org.br\/2019\/wp-content\/uploads\/2019\/01\/sindipetro-marca-cor.png","width":350,"height":126,"caption":"Sindipetro BA"},"image":{"@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sindipetroBa\/","https:\/\/x.com\/SindipetroBahia","https:\/\/www.instagram.com\/sindipetroba\/","https:\/\/www.youtube.com\/c\/SindipetroBahiaOficial"]},{"@type":"Person","@id":"https:\/\/www.sindipetroba.org.br\/2019\/#\/schema\/person\/e61228ef9f981537d4c4eb80f6ea7713","name":"admsp","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/50f06e2b746fe9248099d2c61c12342ab36327e9d413e3171dd7033b84800d96?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50f06e2b746fe9248099d2c61c12342ab36327e9d413e3171dd7033b84800d96?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50f06e2b746fe9248099d2c61c12342ab36327e9d413e3171dd7033b84800d96?s=96&d=mm&r=g","caption":"admsp"}}]}},"_links":{"self":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/3333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/comments?post=3333"}],"version-history":[{"count":4,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/3333\/revisions"}],"predecessor-version":[{"id":3350,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/posts\/3333\/revisions\/3350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media\/3208"}],"wp:attachment":[{"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/media?parent=3333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/categories?post=3333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindipetroba.org.br\/2019\/wp-json\/wp\/v2\/tags?post=3333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}